{"id":2169,"date":"2022-12-16T09:54:24","date_gmt":"2022-12-16T07:54:24","guid":{"rendered":"https:\/\/encontresdexili.org\/entrevista-tatiana-ucraina\/"},"modified":"2022-12-16T10:21:23","modified_gmt":"2022-12-16T08:21:23","slug":"entrevista-tatiana-ucraina","status":"publish","type":"post","link":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/","title":{"rendered":"Entrevista Tatiana UCRA\u00cfNA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[144,140],"tags":[],"class_list":["post-2169","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-encontres-dexili-iii","category-testimonios","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontres d&#039;exili\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cearpv\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T07:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-16T08:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fabrikagrafika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CEARefugio\" \/>\n<meta name=\"twitter:site\" content=\"@CEARefugio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fabrikagrafika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/\"},\"author\":{\"name\":\"fabrikagrafika\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#\\\/schema\\\/person\\\/b8c55dc5b68851135e6c473e558dba67\"},\"headline\":\"Entrevista Tatiana UCRA\u00cfNA\",\"datePublished\":\"2022-12-16T07:54:24+00:00\",\"dateModified\":\"2022-12-16T08:21:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/entrevista-tatiana-ucraina.jpg\",\"articleSection\":[\"Encontres d\u2019Exili III\",\"Testimonios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/\",\"name\":\"Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/entrevista-tatiana-ucraina.jpg\",\"datePublished\":\"2022-12-16T07:54:24+00:00\",\"dateModified\":\"2022-12-16T08:21:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/entrevista-tatiana-ucraina.jpg\",\"contentUrl\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/entrevista-tatiana-ucraina.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/entrevista-tatiana-ucraina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/demo-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista Tatiana UCRA\u00cfNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/\",\"name\":\"Encontres d'exili\",\"description\":\"Una mirada desde nuestra memoria\",\"publisher\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#organization\",\"name\":\"Comissi\u00f3 d\u2019Ajuda al Refugiat del Pa\u00eds Valenci\u00e0\",\"alternateName\":\"CEAR PV\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/CEAR.PaisValencia-vectorizado-300x171-2.jpg\",\"contentUrl\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/CEAR.PaisValencia-vectorizado-300x171-2.jpg\",\"width\":300,\"height\":171,\"caption\":\"Comissi\u00f3 d\u2019Ajuda al Refugiat del Pa\u00eds Valenci\u00e0\"},\"image\":{\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cearpv\",\"https:\\\/\\\/x.com\\\/CEARefugio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/es\\\/#\\\/schema\\\/person\\\/b8c55dc5b68851135e6c473e558dba67\",\"name\":\"fabrikagrafika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/litespeed\\\/avatar\\\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117\",\"url\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/litespeed\\\/avatar\\\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117\",\"contentUrl\":\"https:\\\/\\\/encontresdexili.org\\\/wp-content\\\/litespeed\\\/avatar\\\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117\",\"caption\":\"fabrikagrafika\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili","og_url":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/","og_site_name":"Encontres d&#039;exili","article_publisher":"https:\/\/www.facebook.com\/cearpv","article_published_time":"2022-12-16T07:54:24+00:00","article_modified_time":"2022-12-16T08:21:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg","type":"image\/jpeg"}],"author":"fabrikagrafika","twitter_card":"summary_large_image","twitter_creator":"@CEARefugio","twitter_site":"@CEARefugio","twitter_misc":{"Escrito por":"fabrikagrafika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#article","isPartOf":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/"},"author":{"name":"fabrikagrafika","@id":"https:\/\/encontresdexili.org\/es\/#\/schema\/person\/b8c55dc5b68851135e6c473e558dba67"},"headline":"Entrevista Tatiana UCRA\u00cfNA","datePublished":"2022-12-16T07:54:24+00:00","dateModified":"2022-12-16T08:21:23+00:00","mainEntityOfPage":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/"},"wordCount":4,"publisher":{"@id":"https:\/\/encontresdexili.org\/es\/#organization"},"image":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg","articleSection":["Encontres d\u2019Exili III","Testimonios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/","url":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/","name":"Entrevista Tatiana UCRA\u00cfNA &#8226; Encontres d&#039;exili","isPartOf":{"@id":"https:\/\/encontresdexili.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#primaryimage"},"image":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg","datePublished":"2022-12-16T07:54:24+00:00","dateModified":"2022-12-16T08:21:23+00:00","breadcrumb":{"@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#primaryimage","url":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg","contentUrl":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2022\/12\/entrevista-tatiana-ucraina.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/encontresdexili.org\/es\/entrevista-tatiana-ucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/encontresdexili.org\/es\/demo-home\/"},{"@type":"ListItem","position":2,"name":"Entrevista Tatiana UCRA\u00cfNA"}]},{"@type":"WebSite","@id":"https:\/\/encontresdexili.org\/es\/#website","url":"https:\/\/encontresdexili.org\/es\/","name":"Encontres d'exili","description":"Una mirada desde nuestra memoria","publisher":{"@id":"https:\/\/encontresdexili.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encontresdexili.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/encontresdexili.org\/es\/#organization","name":"Comissi\u00f3 d\u2019Ajuda al Refugiat del Pa\u00eds Valenci\u00e0","alternateName":"CEAR PV","url":"https:\/\/encontresdexili.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/encontresdexili.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2020\/11\/CEAR.PaisValencia-vectorizado-300x171-2.jpg","contentUrl":"https:\/\/encontresdexili.org\/wp-content\/uploads\/2020\/11\/CEAR.PaisValencia-vectorizado-300x171-2.jpg","width":300,"height":171,"caption":"Comissi\u00f3 d\u2019Ajuda al Refugiat del Pa\u00eds Valenci\u00e0"},"image":{"@id":"https:\/\/encontresdexili.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cearpv","https:\/\/x.com\/CEARefugio"]},{"@type":"Person","@id":"https:\/\/encontresdexili.org\/es\/#\/schema\/person\/b8c55dc5b68851135e6c473e558dba67","name":"fabrikagrafika","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/encontresdexili.org\/wp-content\/litespeed\/avatar\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117","url":"https:\/\/encontresdexili.org\/wp-content\/litespeed\/avatar\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117","contentUrl":"https:\/\/encontresdexili.org\/wp-content\/litespeed\/avatar\/7162378195fb5493f62c5832ea49522f.jpg?ver=1787818117","caption":"fabrikagrafika"}}]}},"_links":{"self":[{"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/posts\/2169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/comments?post=2169"}],"version-history":[{"count":2,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/posts\/2169\/revisions"}],"predecessor-version":[{"id":2199,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/posts\/2169\/revisions\/2199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/media\/2168"}],"wp:attachment":[{"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/media?parent=2169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/categories?post=2169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encontresdexili.org\/es\/wp-json\/wp\/v2\/tags?post=2169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}